{"id":38520,"date":"2016-12-27T16:03:42","date_gmt":"2016-12-27T16:03:42","guid":{"rendered":"https:\/\/www.myaquastore.com\/product\/meersalz-meerquelle-coral-korallensalz-67-kg-flasche-quelle\/"},"modified":"2025-03-16T08:56:03","modified_gmt":"2025-03-16T08:56:03","slug":"meersalz-meerquelle-coral-korallensalz-67-kg-flasche-quelle","status":"publish","type":"product","link":"https:\/\/www.myaquastore.com\/de\/produkt\/meersalz-meerquelle-coral-korallensalz-67-kg-flasche-quelle\/","title":{"rendered":"Meersalz Meerquelle Coral Korallensalz 6,7 kg Flasche Quelle"},"content":{"rendered":"<h2>Produktbeschreibung <\/h2>\n<p>&amp;Nbsp; f\u00fcr <\/p>\n<p><a><img class=\" size-large=\"><\/a><\/p>\n<p>MARINE SOURCES Quelle \ufffd\ufffd Korallenmeersalz mit einer modifizierten deutschen neuesten Rezepturentwicklung ist bestrebt, den nat\u00fcrlichen Meerwasserkorallenstandard nachzubilden, der die Grundelemente und Spurenelemente enth\u00e4lt, die f\u00fcr ein nat\u00fcrliches Korallenriffwasser notwendig sind. Eine verbesserte Version von Kalzium, Magnesium und Strontium kann bereitgestellt werden, um alle Bed\u00fcrfnisse des Korallenwachstums zu erf\u00fcllen und das Wachstum der Korallenskelettstruktur zu beschleunigen sowie die Vitalit\u00e4t und Widerstandskraft der Korallen zu verbessern. <br \/> Schnell l\u00f6slich, freies Phosphat und Nitrat. <br \/> Achtung: Nur zur Verwendung in Aquakulturen. <br \/> Au\u00dferhalb der Reichweite von Kindern aufbewahren! <br \/> Spezifikationen: 6,7 kg in Flaschen <br \/> Komponentenkonfiguration: 6,7 kg, anwendbar f\u00fcr Wasser von 175 bis 200 Litern <\/p>\n<p>&amp;Nbsp; f\u00fcr <\/p>\n<p><a><img class=\" size-full=\"><\/a><\/p>\n<p><\/p>\n<p><a><img class=\" size-full=\"><\/a><\/p>\n<p><a><img class=\" size-full=\"><\/a><\/p>\n<p><a><img class=\" size-full=\"><\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Meersalz Meerquelle Coral Korallensalz 6,7 kg Flasche Quelle<\/p>\n","protected":false},"featured_media":6224,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1313],"product_tag":[],"class_list":{"0":"post-38520","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-eiweisabschaumer","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.myaquastore.com\/de\/wp-json\/wp\/v2\/product\/38520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myaquastore.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.myaquastore.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.myaquastore.com\/de\/wp-json\/wp\/v2\/comments?post=38520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myaquastore.com\/de\/wp-json\/wp\/v2\/media\/6224"}],"wp:attachment":[{"href":"https:\/\/www.myaquastore.com\/de\/wp-json\/wp\/v2\/media?parent=38520"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.myaquastore.com\/de\/wp-json\/wp\/v2\/product_brand?post=38520"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.myaquastore.com\/de\/wp-json\/wp\/v2\/product_cat?post=38520"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.myaquastore.com\/de\/wp-json\/wp\/v2\/product_tag?post=38520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}